{"id":16129,"date":"2018-05-01T05:34:24","date_gmt":"2018-05-01T05:34:24","guid":{"rendered":"http:\/\/wp.kodesolution.work\/personal\/j\/charitab\/demo\/?page_id=1827"},"modified":"2020-01-13T08:28:03","modified_gmt":"2020-01-13T08:28:03","slug":"info-list","status":"publish","type":"page","link":"https:\/\/aemedbill.com\/index.php\/ultimate-addons-vc-shortcodes\/info-list\/","title":{"rendered":"Info List"},"content":{"rendered":"<p>\t\t\t\t[vc_row animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left square with_bg\"><li class=\"icon_list_item\" style=\" font-size:105px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:35px;border-width:1px;border-style:solid;background:#ffffff;color:#dd3333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/cd_6_flat.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4429\" style=\"font-size:35px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4429 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Research and Planning<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4429 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:105px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:35px;border-width:1px;border-style:solid;background:#ffffff;color:#dd3333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/cd_2_angle.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6333\" style=\"font-size:35px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-6333 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Prototyping and designing<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6333 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:105px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:35px;border-width:1px;border-style:solid;background:#ffffff;color:#dd3333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/poster_5_up.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7311\" style=\"font-size:35px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7311 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Web development<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7311 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:105px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:35px;border-width:1px;border-style:solid;background:#ffffff;color:#dd3333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/cd_3_angle.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7283\" style=\"font-size:35px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7283 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Client revision and improvement<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7283 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:105px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:35px;border-width:1px;border-style:solid;background:#ffffff;color:#dd3333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/hoodie_2_front.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4853\" style=\"font-size:35px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4853 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Finalizing and making it alive<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4853 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><\/ul><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle no_bg\"><li class=\"icon_list_item\" style=\" font-size:92px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:30px;border-width:1px;border-style:none;color:#dd3333;border-color:#333333;\"><i class=\"Defaults-code\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5921\" style=\"font-size:30px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5921 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Powerful Admin <\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5921 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #e4e4e4;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:92px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:30px;border-width:1px;border-style:none;color:#dd3333;border-color:#333333;\"><i class=\"Defaults-life-bouy life-buoy life-ring life-saver support\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7548\" style=\"font-size:30px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7548 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Free Updated &amp; Support<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7548 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #e4e4e4;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:92px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:30px;border-width:1px;border-style:none;color:#dd3333;border-color:#333333;\"><i class=\"Defaults-bolt flash\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7023\" style=\"font-size:30px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7023 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Lightning Fast<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7023 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #e4e4e4;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:92px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:30px;border-width:1px;border-style:none;color:#dd3333;border-color:#333333;\"><i class=\"Defaults-eye\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5424\" style=\"font-size:30px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5424 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Retina Ready<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5424 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #e4e4e4;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:92px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:30px;border-width:1px;border-style:none;color:#dd3333;border-color:#333333;\"><i class=\"Defaults-database\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7321\" style=\"font-size:30px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7321 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Incredibly Flexible<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7321 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #e4e4e4;\"><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1525325244128{background-color: #fcfbf8 !important;}&#8221; bg_color_value=&#8221;#fcfbf8&#8243; animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list right square with_bg\"><li class=\"icon_list_item\" style=\" font-size:75px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:25px;border-width:2px;border-style:solid;background:#ccc9c8;color:#ffffff;border-color:#ededed;\"><i class=\"Defaults-cog gear\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3586\" style=\"font-size:25px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-3586 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\"> Completely Customizable<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3586 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Curabitur arcu erat, accumsan id imperdiet et, porttitor at sem. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-left-width: 1px;border-left-style: dashed;border-color: #d3d3d9;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:75px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:25px;border-width:2px;border-style:solid;background:#ccc9c8;color:#ffffff;border-color:#ededed;\"><i class=\"Defaults-desktop\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4596\" style=\"font-size:25px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4596 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Browser Compatibility<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4596 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Curabitur arcu erat, accumsan id imperdiet et, porttitor at sem. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-left-width: 1px;border-left-style: dashed;border-color: #d3d3d9;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:75px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:25px;border-width:2px;border-style:solid;background:#ccc9c8;color:#ffffff;border-color:#ededed;\"><i class=\"Defaults-comments-o\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3469\" style=\"font-size:25px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-3469 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\"> Excellent Support<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3469 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Curabitur arcu erat, accumsan id imperdiet et, porttitor at sem. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-left-width: 1px;border-left-style: dashed;border-color: #d3d3d9;\"><\/div><\/li><\/ul><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left square with_bg\"><li class=\"icon_list_item\" style=\" font-size:75px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:25px;border-width:2px;border-style:solid;background:#ccc9c8;color:#ffffff;border-color:#ededed;\"><i class=\"Defaults-archive\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1192\" style=\"font-size:25px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-1192 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Good All-Purpose Design<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1192 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Curabitur arcu erat, accumsan id imperdiet et, porttitor at sem. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #d3d3d9;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:75px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:25px;border-width:2px;border-style:solid;background:#ccc9c8;color:#ffffff;border-color:#ededed;\"><i class=\"Defaults-search\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4435\" style=\"font-size:25px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4435 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Brand New Features <\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4435 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Curabitur arcu erat, accumsan id imperdiet et, porttitor at sem. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #d3d3d9;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:75px;\"><div class=\"icon_list_icon\" data-animation=\"bounceIn\" data-animation-delay=\"03\" style=\"font-size:25px;border-width:2px;border-style:solid;background:#ccc9c8;color:#ffffff;border-color:#ededed;\"><i class=\"Defaults-rocket\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9942\" style=\"font-size:25px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-9942 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Done Awesome<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9942 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Curabitur arcu erat, accumsan id imperdiet et, porttitor at sem. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #d3d3d9;\"><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row][vc_row bg_color=&#8221;#ffffff&#8221; padding=&#8221;40px 0px 0px 0px&#8221; css=&#8221;.vc_custom_1525325258983{background-color: #ffffff !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:81px;\"><div class=\"icon_list_icon\" data-animation=\"swing\" data-animation-delay=\"03\" style=\"font-size:27px;border-width:1px;border-style:none;background:#e8e8e8;color:#333333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/cd_2_angle.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8957\" style=\"font-size:27px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8957 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Crafted with Love<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8957 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #bcbcbc;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:81px;\"><div class=\"icon_list_icon\" data-animation=\"fadeInUpBig\" data-animation-delay=\"03\" style=\"font-size:27px;border-width:1px;border-style:none;background:#e8e8e8;color:#333333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/poster_5_up.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5844\" style=\"font-size:27px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5844 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Crafted with Love<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5844 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #bcbcbc;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:81px;\"><div class=\"icon_list_icon\" data-animation=\"rotateIn\" data-animation-delay=\"03\" style=\"font-size:27px;border-width:1px;border-style:none;background:#e8e8e8;color:#333333;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/hoodie_3_front.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4796\" style=\"font-size:27px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4796 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Mobile Ready<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4796 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Pellentesque in ipsum id orci porta dapibus. Praesent sapien massa, convallis a pellentesque nec, egestas non nisi.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #bcbcbc;\"><\/div><\/li><\/ul><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle no_bg\"><li class=\"icon_list_item\" style=\" font-size:74px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;color:#e6e6e6;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/hoodie_3_front.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4361\" style=\"font-size:24px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4361 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">This is an icon list<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4361 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Write a short or logn description about this list item. You can also use HTML tags for formatting<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:74px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;color:#e6e6e6;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/poster_3_up.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8487\" style=\"font-size:24px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8487 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">This is an icon list<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8487 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Write a short or logn description about this list item. You can also use HTML tags for formatting<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:74px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;color:#e6e6e6;border-color:#333333;\"><img decoding=\"async\" class=\"list-img-icon\" alt=\"null\" src=\"https:\/\/aemedbill.com\/wp-content\/uploads\/2013\/06\/cd_1_angle.jpg\"\/><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4088\" style=\"font-size:24px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4088 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">This is an icon list<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4088 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Write a short or logn description about this list item. You can also use HTML tags for formatting<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row]\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1525325244128{background-color: #fcfbf8 !important;}&#8221; bg_color_value=&#8221;#fcfbf8&#8243; animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row bg_color=&#8221;#ffffff&#8221; padding=&#8221;40px 0px&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1912,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-16129","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/pages\/16129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/comments?post=16129"}],"version-history":[{"count":1,"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/pages\/16129\/revisions"}],"predecessor-version":[{"id":22874,"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/pages\/16129\/revisions\/22874"}],"up":[{"embeddable":true,"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/pages\/1912"}],"wp:attachment":[{"href":"https:\/\/aemedbill.com\/index.php\/wp-json\/wp\/v2\/media?parent=16129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}